{"id":3267,"date":"2018-02-15T12:54:14","date_gmt":"2018-02-15T10:54:14","guid":{"rendered":"http:\/\/exteriorscastellar.com\/?page_id=3267"},"modified":"2018-02-15T12:54:14","modified_gmt":"2018-02-15T10:54:14","slug":"al15-construccion-de-una-terraza-volada-de-madera","status":"publish","type":"page","link":"https:\/\/exteriorscastellar.com\/es\/galeria-de-trabajos\/otros\/al15-construccion-de-una-terraza-volada-de-madera\/","title":{"rendered":"AL15 Construcci\u00f3n de una terraza volada de madera"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_full-6126cab7d8fab8d08143dd2dacdf673c\">\n.flex_column.av-av_one_full-6126cab7d8fab8d08143dd2dacdf673c{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_full-6126cab7d8fab8d08143dd2dacdf673c av_one_full  avia-builder-el-0  avia-builder-el-no-sibling  first flex_column_div av-zero-column-padding  '     ><p><section  class='av_textblock_section av-av_textblock-2de302bf1aa3cf4c9157dbe6f50ac7eb '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>Proceso de construcci\u00f3n de una terraza volada.<\/p>\n<p>Alrededor de una casa bioclim\u00e1tica que dispone de un terreno con gran desnivel hemos realizado esta <strong>terraza volada en la poblaci\u00f3n de Sant Feliu del Rac\u00f3 (Barcelona)<\/strong>, hecha con una estructura de vigas y pilares de acero y suelo de madera tropical de ipe. Tambi\u00e9n hemos fabricado e instalado una barandilla perimetral en la <strong>terraza volada<\/strong>, hecha con pasamanos verticales y cuatro tubos de acero horizontales. Todo el acero ha sido pintado con una capa de imprimaci\u00f3n y dos de oxyron.<\/p>\n<\/div><\/section><br \/>\n<div id='av-masonry-1' class='av-masonry av-av_masonry_gallery-429d4c597db3437a88c9dbb85f7bcf25 noHover av-fixed-size av-large-gap av-hover-overlay- av-masonry-animation-active av-masonry-col-flexible av-caption-always av-caption-style- av-masonry-gallery ' data-post_id=\"3267\"><div class=\"av-masonry-container isotope av-js-disabled\"><div class='av-masonry-entry isotope-item av-masonry-item-no-image '><\/div><a href=\"https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180109_124006-1030x773.jpg\" data-srcset=\"https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180109_124006-1030x773.jpg 1030w, https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180109_124006-300x225.jpg 300w, https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180109_124006-705x529.jpg 705w, https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180109_124006-450x338.jpg 450w, https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180109_124006.jpg 1200w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\"  aria-label=\"image 20180109_124006\"  id='av-masonry-1-item-4223' data-av-masonry-item='4223' class='av-masonry-entry isotope-item post-4223 attachment type-attachment status-inherit hentry  av-masonry-item-with-image' title=\"20180109_124006\" alt=\"\"    itemprop=\"thumbnailUrl\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container' style=\"background-image: url(https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180109_124006-705x529.jpg);\"  title=\"20180109_124006\" ><\/div><\/div><\/figure><\/a><!--end av-masonry entry--><a href=\"https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180109_124040-1030x773.jpg\" data-srcset=\"https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180109_124040-1030x773.jpg 1030w, https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180109_124040-300x225.jpg 300w, https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180109_124040-705x529.jpg 705w, https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180109_124040-450x338.jpg 450w, https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180109_124040.jpg 1200w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\"  aria-label=\"image 20180109_124040\"  id='av-masonry-1-item-4224' data-av-masonry-item='4224' class='av-masonry-entry isotope-item post-4224 attachment type-attachment status-inherit hentry  av-masonry-item-with-image' title=\"20180109_124040\" alt=\"\"    itemprop=\"thumbnailUrl\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container' style=\"background-image: url(https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180109_124040-705x529.jpg);\"  title=\"20180109_124040\" ><\/div><\/div><\/figure><\/a><!--end av-masonry entry--><a href=\"https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180117_143444-1030x773.jpg\" data-srcset=\"https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180117_143444-1030x773.jpg 1030w, https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180117_143444-300x225.jpg 300w, https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180117_143444-705x529.jpg 705w, https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180117_143444-450x338.jpg 450w, https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180117_143444.jpg 1200w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\"  aria-label=\"image 20180117_143444\"  id='av-masonry-1-item-4225' data-av-masonry-item='4225' class='av-masonry-entry isotope-item post-4225 attachment type-attachment status-inherit hentry  av-masonry-item-with-image' title=\"20180117_143444\" alt=\"\"    itemprop=\"thumbnailUrl\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container' style=\"background-image: url(https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180117_143444-705x529.jpg);\"  title=\"20180117_143444\" ><\/div><\/div><\/figure><\/a><!--end av-masonry entry--><a href=\"https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180117_143612-1030x773.jpg\" data-srcset=\"https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180117_143612-1030x773.jpg 1030w, https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180117_143612-300x225.jpg 300w, https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180117_143612-705x529.jpg 705w, https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180117_143612-450x338.jpg 450w, https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180117_143612.jpg 1200w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\"  aria-label=\"image 20180117_143612\"  id='av-masonry-1-item-4226' data-av-masonry-item='4226' class='av-masonry-entry isotope-item post-4226 attachment type-attachment status-inherit hentry  av-masonry-item-with-image' title=\"20180117_143612\" alt=\"\"    itemprop=\"thumbnailUrl\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container' style=\"background-image: url(https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180117_143612-705x529.jpg);\"  title=\"20180117_143612\" ><\/div><\/div><\/figure><\/a><!--end av-masonry entry--><a href=\"https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180119_125947-1030x773.jpg\" data-srcset=\"https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180119_125947-1030x773.jpg 1030w, https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180119_125947-300x225.jpg 300w, https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180119_125947-705x529.jpg 705w, https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180119_125947-450x338.jpg 450w, https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180119_125947.jpg 1200w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\"  aria-label=\"image 20180119_125947\"  id='av-masonry-1-item-4227' data-av-masonry-item='4227' class='av-masonry-entry isotope-item post-4227 attachment type-attachment status-inherit hentry  av-masonry-item-with-image' title=\"20180119_125947\" alt=\"\"    itemprop=\"thumbnailUrl\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container' style=\"background-image: url(https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180119_125947-705x529.jpg);\"  title=\"20180119_125947\" ><\/div><\/div><\/figure><\/a><!--end av-masonry entry--><a href=\"https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180119_130124-1030x773.jpg\" data-srcset=\"https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180119_130124-1030x773.jpg 1030w, https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180119_130124-300x225.jpg 300w, https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180119_130124-705x529.jpg 705w, https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180119_130124-450x338.jpg 450w, https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180119_130124.jpg 1200w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\"  aria-label=\"image 20180119_130124\"  id='av-masonry-1-item-4228' data-av-masonry-item='4228' class='av-masonry-entry isotope-item post-4228 attachment type-attachment status-inherit hentry  av-masonry-item-with-image' title=\"20180119_130124\" alt=\"\"    itemprop=\"thumbnailUrl\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container' style=\"background-image: url(https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180119_130124-705x529.jpg);\"  title=\"20180119_130124\" ><\/div><\/div><\/figure><\/a><!--end av-masonry entry--><a href=\"https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180129_142122-1030x773.jpg\" data-srcset=\"https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180129_142122-1030x773.jpg 1030w, https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180129_142122-300x225.jpg 300w, https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180129_142122-705x529.jpg 705w, https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180129_142122-450x338.jpg 450w, https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180129_142122.jpg 1200w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\"  aria-label=\"image 20180129_142122\"  id='av-masonry-1-item-4229' data-av-masonry-item='4229' class='av-masonry-entry isotope-item post-4229 attachment type-attachment status-inherit hentry  av-masonry-item-with-image' title=\"20180129_142122\" alt=\"\"    itemprop=\"thumbnailUrl\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container' style=\"background-image: url(https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180129_142122-705x529.jpg);\"  title=\"20180129_142122\" ><\/div><\/div><\/figure><\/a><!--end av-masonry entry--><a href=\"https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180129_142344-1030x773.jpg\" data-srcset=\"https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180129_142344-1030x773.jpg 1030w, https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180129_142344-300x225.jpg 300w, https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180129_142344-705x529.jpg 705w, https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180129_142344-450x338.jpg 450w, https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180129_142344.jpg 1200w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\"  aria-label=\"image 20180129_142344\"  id='av-masonry-1-item-4230' data-av-masonry-item='4230' class='av-masonry-entry isotope-item post-4230 attachment type-attachment status-inherit hentry  av-masonry-item-with-image' title=\"20180129_142344\" alt=\"\"    itemprop=\"thumbnailUrl\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container' style=\"background-image: url(https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180129_142344-705x529.jpg);\"  title=\"20180129_142344\" ><\/div><\/div><\/figure><\/a><!--end av-masonry entry--><a href=\"https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180129_142449-1030x773.jpg\" data-srcset=\"https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180129_142449-1030x773.jpg 1030w, https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180129_142449-300x225.jpg 300w, https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180129_142449-705x529.jpg 705w, https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180129_142449-450x338.jpg 450w, https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180129_142449.jpg 1200w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\"  aria-label=\"image 20180129_142449\"  id='av-masonry-1-item-4231' data-av-masonry-item='4231' class='av-masonry-entry isotope-item post-4231 attachment type-attachment status-inherit hentry  av-masonry-item-with-image' title=\"20180129_142449\" alt=\"\"    itemprop=\"thumbnailUrl\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container' style=\"background-image: url(https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180129_142449-705x529.jpg);\"  title=\"20180129_142449\" ><\/div><\/div><\/figure><\/a><!--end av-masonry entry--><a href=\"https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180129_142502-1030x773.jpg\" data-srcset=\"https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180129_142502-1030x773.jpg 1030w, https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180129_142502-300x225.jpg 300w, https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180129_142502-705x529.jpg 705w, https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180129_142502-450x338.jpg 450w, https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180129_142502.jpg 1200w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\"  aria-label=\"image 20180129_142502\"  id='av-masonry-1-item-4232' data-av-masonry-item='4232' class='av-masonry-entry isotope-item post-4232 attachment type-attachment status-inherit hentry  av-masonry-item-with-image' title=\"20180129_142502\" alt=\"\"    itemprop=\"thumbnailUrl\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container' style=\"background-image: url(https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180129_142502-705x529.jpg);\"  title=\"20180129_142502\" ><\/div><\/div><\/figure><\/a><!--end av-masonry entry--><a href=\"https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180129_142520-773x1030.jpg\" data-srcset=\"https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180129_142520-773x1030.jpg 773w, https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180129_142520-225x300.jpg 225w, https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180129_142520-529x705.jpg 529w, https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180129_142520-450x600.jpg 450w, https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180129_142520.jpg 900w\" data-sizes=\"(max-width: 773px) 100vw, 773px\"  aria-label=\"image 20180129_142520\"  id='av-masonry-1-item-4233' data-av-masonry-item='4233' class='av-masonry-entry isotope-item post-4233 attachment type-attachment status-inherit hentry  av-masonry-item-with-image' title=\"20180129_142520\" alt=\"\"    itemprop=\"thumbnailUrl\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container' style=\"background-image: url(https:\/\/exteriorscastellar.com\/wp-content\/uploads\/2018\/02\/20180129_142520-529x705.jpg);\"  title=\"20180129_142520\" ><\/div><\/div><\/figure><\/a><!--end av-masonry entry--><\/div><\/div><\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Alrededor de una casa bioclim\u00e1tica que dispone de un terreno con gran desnivel hemos realizado esta terraza volada en la poblaci\u00f3n de Sant Feliu del Rac\u00f3 (Barcelona)<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":1692,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"slim_seo":{"title":"AL15 Construcci\u00f3n de una terraza volada de madera - Exteriors Castellar","description":"Alrededor de una casa bioclim\u00e1tica que dispone de un terreno con gran desnivel hemos realizado esta terraza volada en la poblaci\u00f3n de Sant Feliu del Rac\u00f3 (Barce"},"footnotes":"","_wp_rev_ctl_limit":""},"class_list":["post-3267","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/exteriorscastellar.com\/es\/wp-json\/wp\/v2\/pages\/3267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exteriorscastellar.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/exteriorscastellar.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/exteriorscastellar.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/exteriorscastellar.com\/es\/wp-json\/wp\/v2\/comments?post=3267"}],"version-history":[{"count":3,"href":"https:\/\/exteriorscastellar.com\/es\/wp-json\/wp\/v2\/pages\/3267\/revisions"}],"predecessor-version":[{"id":3270,"href":"https:\/\/exteriorscastellar.com\/es\/wp-json\/wp\/v2\/pages\/3267\/revisions\/3270"}],"up":[{"embeddable":true,"href":"https:\/\/exteriorscastellar.com\/es\/wp-json\/wp\/v2\/pages\/1692"}],"wp:attachment":[{"href":"https:\/\/exteriorscastellar.com\/es\/wp-json\/wp\/v2\/media?parent=3267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}